{"id":3393656,"date":"2026-05-06T12:35:06","date_gmt":"2026-05-06T09:35:06","guid":{"rendered":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/"},"modified":"2026-05-13T01:00:31","modified_gmt":"2026-05-12T22:00:31","slug":"kaelakee-sidpa-champagne-gem","status":"publish","type":"product","link":"https:\/\/tallinndesignhouse.com\/en\/toode\/kaelakee-sidpa-champagne-gem\/","title":{"rendered":"Necklace Sidpa Champagne Gem"},"content":{"rendered":"<p>The SIDPA necklace by the brand NRTN is crafted from 925 sterling silver and finished with 18K gold vermeil, set with a champagne-toned zirconia stone. Its balanced form and refined finish create a timeless piece suit\u0430ble for both everyday wear and special occasions. Inspired by the BARDO collection, it reflects transformation and quiet strength.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>The SIDPA necklace by the brand NRTN is crafted from 925 sterling silver and finished with 18K gold vermeil, set with a champagne-toned zirconia stone. Its balanced form and refined finish create a timeless piece suit\u0430ble for both everyday wear and special occasions. Inspired by the BARDO collection, it reflects transformation and quiet strength.<\/p>\n","protected":false},"featured_media":3393728,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2127,3223],"product_tag":[2819],"class_list":{"0":"post-3393656","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-necklaces","7":"product_cat-jewellery-en","8":"product_tag-women","9":"pa_brand-nrtn-en","11":"first","12":"instock","13":"taxable","14":"shipping-taxable","15":"purchasable","16":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Necklace Sidpa Champagne Gem - Tallinn Design House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Necklace Sidpa Champagne Gem - Tallinn Design House\" \/>\n<meta property=\"og:description\" content=\"The SIDPA necklace by the brand NRTN is crafted from 925 sterling silver and finished with 18K gold vermeil, set with a champagne-toned zirconia stone. Its balanced form and refined finish create a timeless piece suit\u0430ble for both everyday wear and special occasions. Inspired by the BARDO collection, it reflects transformation and quiet strength.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/\" \/>\n<meta property=\"og:site_name\" content=\"Tallinn Design House\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T22:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"1350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/\",\"url\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/\",\"name\":\"Necklace Sidpa Champagne Gem - Tallinn Design House\",\"isPartOf\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg\",\"datePublished\":\"2026-05-06T09:35:06+00:00\",\"dateModified\":\"2026-05-12T22:00:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage\",\"url\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg\",\"contentUrl\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg\",\"width\":1080,\"height\":1350,\"caption\":\"NRTN Tallinn Design House\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tallinndesignhouse.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/tallinndesignhouse.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Necklace Sidpa Champagne Gem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tallinndesignhouse.com\/#website\",\"url\":\"https:\/\/tallinndesignhouse.com\/\",\"name\":\"Tallinn Design House\",\"description\":\"Eesti disain Rotermanni kvartalis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tallinndesignhouse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Necklace Sidpa Champagne Gem - Tallinn Design House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/","og_locale":"en_US","og_type":"article","og_title":"Necklace Sidpa Champagne Gem - Tallinn Design House","og_description":"The SIDPA necklace by the brand NRTN is crafted from 925 sterling silver and finished with 18K gold vermeil, set with a champagne-toned zirconia stone. Its balanced form and refined finish create a timeless piece suit\u0430ble for both everyday wear and special occasions. Inspired by the BARDO collection, it reflects transformation and quiet strength.","og_url":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/","og_site_name":"Tallinn Design House","article_modified_time":"2026-05-12T22:00:31+00:00","og_image":[{"width":1080,"height":1350,"url":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/","url":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/","name":"Necklace Sidpa Champagne Gem - Tallinn Design House","isPartOf":{"@id":"https:\/\/tallinndesignhouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage"},"image":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage"},"thumbnailUrl":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg","datePublished":"2026-05-06T09:35:06+00:00","dateModified":"2026-05-12T22:00:31+00:00","breadcrumb":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#primaryimage","url":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg","contentUrl":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2026\/05\/NRTN-Tallinn-Design-House-2.jpg","width":1080,"height":1350,"caption":"NRTN Tallinn Design House"},{"@type":"BreadcrumbList","@id":"https:\/\/tallinndesignhouse.com\/toode\/kaelakee-sidpa-champagne-gem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tallinndesignhouse.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tallinndesignhouse.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Necklace Sidpa Champagne Gem"}]},{"@type":"WebSite","@id":"https:\/\/tallinndesignhouse.com\/#website","url":"https:\/\/tallinndesignhouse.com\/","name":"Tallinn Design House","description":"Eesti disain Rotermanni kvartalis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tallinndesignhouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product\/3393656","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/media\/3393728"}],"wp:attachment":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/media?parent=3393656"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_brand?post=3393656"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_cat?post=3393656"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_tag?post=3393656"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}