{"id":37038,"date":"2022-04-13T12:57:18","date_gmt":"2022-04-13T09:57:18","guid":{"rendered":"https:\/\/karlerik.octadev.ee\/designhouse\/toode\/puksid-celeste\/"},"modified":"2026-05-13T00:55:42","modified_gmt":"2026-05-12T21:55:42","slug":"puksid-celeste","status":"publish","type":"product","link":"https:\/\/tallinndesignhouse.com\/en\/toode\/puksid-celeste\/","title":{"rendered":"Pants Celeste"},"content":{"rendered":"<p>High waist pants by August. Featuring 2 pockets in the back. Fits true to size. Mid-weight non stretchy organic cotton. Material: 100% organic cotton. Care: gentle cycle machine wash, medium heat iron reversed side.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>High waist pants by August. Featuring 2 pockets in the back. Fits true to size. Mid-weight non stretchy organic cotton. Material: 100% organic cotton. Care: gentle cycle machine wash, medium heat iron reversed side.<\/p>\n","protected":false},"featured_media":18450,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2013,2837,3552],"product_tag":[2819],"class_list":{"0":"post-37038","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-pants","7":"product_cat-clothes","8":"product_cat-natural-materials-en","9":"product_tag-women","10":"pa_brand-august-en","12":"pa_suurus-34-en","14":"pa_suurus-36-en","16":"pa_suurus-38-en","18":"pa_varv-black-en","19":"pa_varv-grey-en","23":"first","24":"instock","25":"taxable","26":"shipping-taxable","27":"purchasable","28":"product-type-variable"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pants Celeste - Tallinn Design House<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pants Celeste - Tallinn Design House\" \/>\n<meta property=\"og:description\" content=\"High waist pants by August. Featuring 2 pockets in the back. Fits true to size. Mid-weight non stretchy organic cotton. Material: 100% organic cotton. Care: gentle cycle machine wash, medium heat iron reversed side.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/\" \/>\n<meta property=\"og:site_name\" content=\"Tallinn Design House\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-12T21:55:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1463\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/\",\"url\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/\",\"name\":\"Pants Celeste - Tallinn Design House\",\"isPartOf\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg\",\"datePublished\":\"2022-04-13T09:57:18+00:00\",\"dateModified\":\"2026-05-12T21:55:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage\",\"url\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg\",\"contentUrl\":\"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg\",\"width\":1463,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/tallinndesignhouse.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/tallinndesignhouse.com\/en\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pants Celeste\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/tallinndesignhouse.com\/#website\",\"url\":\"https:\/\/tallinndesignhouse.com\/\",\"name\":\"Tallinn Design House\",\"description\":\"Eesti disain Rotermanni kvartalis\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/tallinndesignhouse.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pants Celeste - Tallinn Design House","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/","og_locale":"en_US","og_type":"article","og_title":"Pants Celeste - Tallinn Design House","og_description":"High waist pants by August. Featuring 2 pockets in the back. Fits true to size. Mid-weight non stretchy organic cotton. Material: 100% organic cotton. Care: gentle cycle machine wash, medium heat iron reversed side.","og_url":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/","og_site_name":"Tallinn Design House","article_modified_time":"2026-05-12T21:55:42+00:00","og_image":[{"width":1463,"height":2048,"url":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/","url":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/","name":"Pants Celeste - Tallinn Design House","isPartOf":{"@id":"https:\/\/tallinndesignhouse.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage"},"image":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage"},"thumbnailUrl":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg","datePublished":"2022-04-13T09:57:18+00:00","dateModified":"2026-05-12T21:55:42+00:00","breadcrumb":{"@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#primaryimage","url":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg","contentUrl":"https:\/\/tallinndesignhouse.com\/wp-content\/uploads\/2022\/04\/august_puksid_celeste_hall_web.jpeg","width":1463,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/tallinndesignhouse.com\/toode\/puksid-celeste\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/tallinndesignhouse.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tallinndesignhouse.com\/en\/shop\/"},{"@type":"ListItem","position":3,"name":"Pants Celeste"}]},{"@type":"WebSite","@id":"https:\/\/tallinndesignhouse.com\/#website","url":"https:\/\/tallinndesignhouse.com\/","name":"Tallinn Design House","description":"Eesti disain Rotermanni kvartalis","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tallinndesignhouse.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product\/37038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/media\/18450"}],"wp:attachment":[{"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/media?parent=37038"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_brand?post=37038"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_cat?post=37038"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tallinndesignhouse.com\/en\/wp-json\/wp\/v2\/product_tag?post=37038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}